{"id":788,"date":"2018-09-27T15:40:32","date_gmt":"2018-09-27T13:40:32","guid":{"rendered":"https:\/\/eds.bartels-events.nl\/?page_id=788"},"modified":"2023-03-24T09:19:01","modified_gmt":"2023-03-24T08:19:01","slug":"contact","status":"publish","type":"page","link":"https:\/\/excellentdressagesales.com\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Organization Excellent Dressage Sales<br \/>\nAcademy Bartels<br \/>\nKoestraat 11B<br \/>\n5095 BD Hooge Mierde<br \/>\nE:\u00a0info@excellentdressagesales.com<br \/>\n&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/tpl-contact.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-788","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact - Excellent Dressage Sales<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/excellentdressagesales.com\/en\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact - Excellent Dressage Sales\" \/>\n<meta property=\"og:description\" content=\"Organization Excellent Dressage Sales Academy Bartels Koestraat 11B 5095 BD Hooge Mierde E:\u00a0info@excellentdressagesales.com ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/excellentdressagesales.com\/en\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Excellent Dressage Sales\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-24T08:19:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/excellentdressagesales.com\\\/en\\\/contact\\\/\",\"url\":\"https:\\\/\\\/excellentdressagesales.com\\\/en\\\/contact\\\/\",\"name\":\"Contact - Excellent Dressage Sales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/excellentdressagesales.com\\\/#website\"},\"datePublished\":\"2018-09-27T13:40:32+00:00\",\"dateModified\":\"2023-03-24T08:19:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/excellentdressagesales.com\\\/en\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/excellentdressagesales.com\\\/en\\\/contact\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/excellentdressagesales.com\\\/en\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/excellentdressagesales.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/excellentdressagesales.com\\\/#website\",\"url\":\"https:\\\/\\\/excellentdressagesales.com\\\/\",\"name\":\"Excellent Dressage Sales\",\"description\":\"D\u00e9 dressuurpaarden veiling van Nederland\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/excellentdressagesales.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact - Excellent Dressage Sales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/excellentdressagesales.com\/en\/contact\/","og_locale":"en_US","og_type":"article","og_title":"Contact - Excellent Dressage Sales","og_description":"Organization Excellent Dressage Sales Academy Bartels Koestraat 11B 5095 BD Hooge Mierde E:\u00a0info@excellentdressagesales.com ...","og_url":"https:\/\/excellentdressagesales.com\/en\/contact\/","og_site_name":"Excellent Dressage Sales","article_modified_time":"2023-03-24T08:19:01+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/excellentdressagesales.com\/en\/contact\/","url":"https:\/\/excellentdressagesales.com\/en\/contact\/","name":"Contact - Excellent Dressage Sales","isPartOf":{"@id":"https:\/\/excellentdressagesales.com\/#website"},"datePublished":"2018-09-27T13:40:32+00:00","dateModified":"2023-03-24T08:19:01+00:00","breadcrumb":{"@id":"https:\/\/excellentdressagesales.com\/en\/contact\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/excellentdressagesales.com\/en\/contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/excellentdressagesales.com\/en\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/excellentdressagesales.com\/en\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/excellentdressagesales.com\/#website","url":"https:\/\/excellentdressagesales.com\/","name":"Excellent Dressage Sales","description":"D\u00e9 dressuurpaarden veiling van Nederland","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/excellentdressagesales.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/pages\/788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/comments?post=788"}],"version-history":[{"count":12,"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/pages\/788\/revisions"}],"predecessor-version":[{"id":15551,"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/pages\/788\/revisions\/15551"}],"wp:attachment":[{"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/media?parent=788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}