{"id":825,"date":"2018-09-28T11:46:06","date_gmt":"2018-09-28T09:46:06","guid":{"rendered":"https:\/\/eds.bartels-events.nl\/?page_id=825"},"modified":"2022-03-18T13:15:00","modified_gmt":"2022-03-18T12:15:00","slug":"additional","status":"publish","type":"page","link":"https:\/\/excellentdressagesales.com\/en\/information\/additional\/","title":{"rendered":"Additional"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Insurance<br \/>\nHippoHorseInsurance offer the possibility to insure the horse that you purchase on the EDS &#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":765,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-825","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Additional - Excellent Dressage Sales<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/excellentdressagesales.com\/en\/information\/additional\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Additional - Excellent Dressage Sales\" \/>\n<meta property=\"og:description\" content=\"Insurance HippoHorseInsurance offer the possibility to insure the horse that you purchase on the EDS ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/excellentdressagesales.com\/en\/information\/additional\/\" \/>\n<meta property=\"og:site_name\" content=\"Excellent Dressage Sales\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-18T12:15:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/excellentdressagesales.com\\\/en\\\/information\\\/additional\\\/\",\"url\":\"https:\\\/\\\/excellentdressagesales.com\\\/en\\\/information\\\/additional\\\/\",\"name\":\"Additional - Excellent Dressage Sales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/excellentdressagesales.com\\\/#website\"},\"datePublished\":\"2018-09-28T09:46:06+00:00\",\"dateModified\":\"2022-03-18T12:15:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/excellentdressagesales.com\\\/en\\\/information\\\/additional\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/excellentdressagesales.com\\\/en\\\/information\\\/additional\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/excellentdressagesales.com\\\/en\\\/information\\\/additional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/excellentdressagesales.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Information\",\"item\":\"https:\\\/\\\/excellentdressagesales.com\\\/en\\\/information\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Additional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/excellentdressagesales.com\\\/#website\",\"url\":\"https:\\\/\\\/excellentdressagesales.com\\\/\",\"name\":\"Excellent Dressage Sales\",\"description\":\"D\u00e9 dressuurpaarden veiling van Nederland\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/excellentdressagesales.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Additional - Excellent Dressage Sales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/excellentdressagesales.com\/en\/information\/additional\/","og_locale":"en_US","og_type":"article","og_title":"Additional - Excellent Dressage Sales","og_description":"Insurance HippoHorseInsurance offer the possibility to insure the horse that you purchase on the EDS ...","og_url":"https:\/\/excellentdressagesales.com\/en\/information\/additional\/","og_site_name":"Excellent Dressage Sales","article_modified_time":"2022-03-18T12:15:00+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/excellentdressagesales.com\/en\/information\/additional\/","url":"https:\/\/excellentdressagesales.com\/en\/information\/additional\/","name":"Additional - Excellent Dressage Sales","isPartOf":{"@id":"https:\/\/excellentdressagesales.com\/#website"},"datePublished":"2018-09-28T09:46:06+00:00","dateModified":"2022-03-18T12:15:00+00:00","breadcrumb":{"@id":"https:\/\/excellentdressagesales.com\/en\/information\/additional\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/excellentdressagesales.com\/en\/information\/additional\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/excellentdressagesales.com\/en\/information\/additional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/excellentdressagesales.com\/en\/"},{"@type":"ListItem","position":2,"name":"Information","item":"https:\/\/excellentdressagesales.com\/en\/information\/"},{"@type":"ListItem","position":3,"name":"Additional"}]},{"@type":"WebSite","@id":"https:\/\/excellentdressagesales.com\/#website","url":"https:\/\/excellentdressagesales.com\/","name":"Excellent Dressage Sales","description":"D\u00e9 dressuurpaarden veiling van Nederland","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/excellentdressagesales.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/pages\/825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/comments?post=825"}],"version-history":[{"count":10,"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/pages\/825\/revisions"}],"predecessor-version":[{"id":13107,"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/pages\/825\/revisions\/13107"}],"up":[{"embeddable":true,"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/pages\/765"}],"wp:attachment":[{"href":"https:\/\/excellentdressagesales.com\/en\/wp-json\/wp\/v2\/media?parent=825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}